{"id":439,"date":"2023-03-04T11:35:49","date_gmt":"2023-03-04T11:35:49","guid":{"rendered":"https:\/\/ssc-weissenstein.ch\/?p=439"},"modified":"2023-03-04T11:35:49","modified_gmt":"2023-03-04T11:35:49","slug":"sscw-mitglieder-skitag","status":"publish","type":"post","link":"https:\/\/ssc-weissenstein.ch\/index.php\/2023\/03\/04\/sscw-mitglieder-skitag\/","title":{"rendered":"SSCW Mitglieder Skitag"},"content":{"rendered":"\n<p>Liebe Vereinsmitglieder<br>Der Schneesportclub Weissenstein wird 55 Jahre alt \u2013 ein Grund zum Feiern! Der<br>Startschuss ins Jubil\u00e4umsjahr f\u00e4llt mit dem SSCW-Mitglieder-Skitag, zu welchem wir euch<br>herzlich einladen: Sonntag, 26. M\u00e4rz 2023, beim Tor zur Jungfrauregion \u2013 Grindelwald<\/p>\n\n\n\n<figure class=\"wp-block-table is-style-stripes\"><table><tbody><tr><td>Datum<\/td><td>26.03.2023<\/td><\/tr><tr><td>Treffpunkt<\/td><td>Volg, Oberdorf<\/td><\/tr><tr><td>Uhrzeit<\/td><td>7:15 Uhr<\/td><\/tr><tr><td>Einladungsbrief<\/td><td><a href=\"http:\/\/ssc-weissenstein.ch\/wp-content\/uploads\/2023\/03\/2023_Einladung_Skitag-Mitglieder.pdf\" target=\"_blank\" rel=\"noreferrer noopener\">link<\/a><\/td><\/tr><\/tbody><\/table><\/figure>\n\n\n\n<iframe loading=\"lazy\" src=\"https:\/\/docs.google.com\/forms\/d\/e\/1FAIpQLSeklMqH1GrHp-uOrbr-N-pANVMsYzzSaWbanNrodrBfYl5OqQ\/viewform?embedded=true\" width=\"640\" height=\"1542\" frameborder=\"0\" marginheight=\"0\" marginwidth=\"0\">Wird geladen\u2026<\/iframe>\n","protected":false},"excerpt":{"rendered":"<p>Liebe VereinsmitgliederDer Schneesportclub Weissenstein wird 55 Jahre alt \u2013 ein Grund zum Feiern! DerStartschuss ins Jubil\u00e4umsjahr f\u00e4llt mit dem SSCW-Mitglieder-Skitag, zu welchem wir euchherzlich einladen: Sonntag, 26. M\u00e4rz 2023, beim Tor zur Jungfrauregion \u2013 Grindelwald Datum 26.03.2023 Treffpunkt Volg, Oberdorf Uhrzeit 7:15 Uhr Einladungsbrief link Wird geladen\u2026<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5],"tags":[19,18,15],"class_list":["post-439","post","type-post","status-publish","format-standard","hentry","category-verein","tag-jubilaeum","tag-mitglieder","tag-skitag"],"_links":{"self":[{"href":"https:\/\/ssc-weissenstein.ch\/index.php\/wp-json\/wp\/v2\/posts\/439","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/ssc-weissenstein.ch\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/ssc-weissenstein.ch\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/ssc-weissenstein.ch\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/ssc-weissenstein.ch\/index.php\/wp-json\/wp\/v2\/comments?post=439"}],"version-history":[{"count":4,"href":"https:\/\/ssc-weissenstein.ch\/index.php\/wp-json\/wp\/v2\/posts\/439\/revisions"}],"predecessor-version":[{"id":444,"href":"https:\/\/ssc-weissenstein.ch\/index.php\/wp-json\/wp\/v2\/posts\/439\/revisions\/444"}],"wp:attachment":[{"href":"https:\/\/ssc-weissenstein.ch\/index.php\/wp-json\/wp\/v2\/media?parent=439"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/ssc-weissenstein.ch\/index.php\/wp-json\/wp\/v2\/categories?post=439"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/ssc-weissenstein.ch\/index.php\/wp-json\/wp\/v2\/tags?post=439"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}